{"id":14220,"date":"2018-10-26T23:47:46","date_gmt":"2018-10-27T03:47:46","guid":{"rendered":"https:\/\/traveler.marriott.com\/es\/?p=14220"},"modified":"2018-10-26T23:47:46","modified_gmt":"2018-10-27T03:47:46","slug":"teatro-en-chicago","status":"publish","type":"post","link":"https:\/\/traveler.marriott.com\/es\/cultura-estilo\/teatro-en-chicago\/","title":{"rendered":"Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad"},"content":{"rendered":"<p>Con m\u00e1s de 40 sedes, producciones aclamadas a nivel nacional y una <a href=\"https:\/\/www.choosechicago.com\/events-and-shows\/arts-and-entertainment\/chicago-theatre-week\/\" target=\"_blank\" rel=\"noopener noreferrer\">Semana del Teatro, <\/a> <a href=\"https:\/\/traveler.marriott.com\/chicago\/\" target=\"_blank\" rel=\"noopener noreferrer\">Chicago, Illinois<\/a> se erige como uno de los escenarios art\u00edsticos m\u00e1s din\u00e1micos de Estados Unidos. Y aunque los teatros m\u00e1s frecuentados de la ciudad se encuentran en su propio distrito dentro del Loop, la \u201cSegunda Ciudad\u201d no se queda atr\u00e1s en cuanto a sitios que visitar en sus numerosos vecindarios.<\/p>\n<h2>Magnificent Mile: Broadway y m\u00e1s<\/h2>\n<p style=\"text-align: left\">En el vecindario Magnificent Mile encontrar\u00e1s algunas de las mejores boutiques de lujo, exquisita gastronom\u00eda y vistas que no te puedes perder. La Water Tower, uno de los pocos edificios que sobrevivieron al gran incendio de Chicago en 1871, con una altura de 154 pies (47 m) es actualmente sede del <a href=\"https:\/\/www.choosechicago.com\/events-and-shows\/arts-and-entertainment\/chicago-theatre-week\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lookingglass Theatre<\/a>.<\/p>\n<p>La compa\u00f1\u00eda, galardonada con el premio Tony, se enfoca en espect\u00e1culos originales y adaptaciones contempor\u00e1neas de cuentos cl\u00e1sicos como <i>Alicia en el pa\u00eds de las maravillas, Moby Dick, La isla del tesoro <\/i>y<i> Las mil y una noches<\/i>. Cada representaci\u00f3n pasa por una capacitaci\u00f3n improvisada en todos los aspectos, desde baile hasta actos circenses, de esta forma se garantiza que ninguna sea igual a las dem\u00e1s.<\/p>\n<p>A solo unos pasos se encuentra la <a href=\"http:\/\/www.broadwayinchicago.com\/theatre\/broadway-playhouse\/\" target=\"_blank\" rel=\"noopener noreferrer\">Broadway Playhouse<\/a>, una auditorio con 550 butacas dentro del centro comercial Water Tower Place del vecindario. Ofrece producci\u00f3n antes y fuera de Broadway junto con espect\u00e1culos de magia y actos de comedia.<\/p>\n<p>Antes de asistir al espect\u00e1culo, visita <a href=\"http:\/\/www.spiaggiarestaurant.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Spiaggia<\/a>, un referente del vecindario (favorito de la familia Obama) que ofrece excelente gastronom\u00eda italiana. Goza de las vistas de Magnificent Mile al mismo tiempo que saboreas platillos de inspiraci\u00f3n regional como espagueti con erizo de mar y ajo negro, o lomo de cordero con pesto de habas y hongos morilla. Acompa\u00f1a tu comida con vinos de la lista de la directora de bebidas Rachael Lowe, que es tan vers\u00e1til como asequible.<\/p>\n<p>Despu\u00e9s del teatro, cruza la calle y saborea una copa en <a href=\"https:\/\/www.hyatt.com\/corporate\/restaurants\/nomi\/en\/home.html\" target=\"_blank\" rel=\"noopener noreferrer\">NoMI<\/a>, donde unos cuantos asientos muy codiciados ubicados a lo largo de las ventanas del 8.\u00b0 piso ofrecen a los visitantes vistas sin igual de la Water Tower y de Michigan Avenue. Si apeteces algo dulce, visita <a href=\"https:\/\/www.ghirardelli.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ghirardelli<\/a>, cuya especialidad son los sundaes.<\/p>\n<h2>Hyde Park: Teatro en el campus<\/h2>\n<figure id=\"attachment_14218\" aria-describedby=\"caption-attachment-14218\" style=\"width: 1920px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14218\" src=\"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/1_Chicago_theatres-CourtTheatre.jpg\" alt=\"chicago theater\" width=\"1920\" height=\"960\"><figcaption id=\"caption-attachment-14218\" class=\"wp-caption-text\">No olvides estar atento a las producciones en el Hyde Park de Chicago. (Foto: Ten Photos)<\/figcaption><\/figure>\n<p>Para conocer un sitio con un legado hist\u00f3rico a\u00fan m\u00e1s rico, dir\u00edgete al sur, hacia Hyde Park y <a href=\"http:\/\/www.courttheatre.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Court Theatre<\/a>, que abri\u00f3 sus puertas en 1955 en el campus de la Universidad de Chicago. Su ubicaci\u00f3n es de gran ayuda para los objetivos teatrales de la compa\u00f1\u00eda de revivir obras maestras olvidadas, descubrir los cl\u00e1sicos modernos y explorar la oferta teatral afroamericana.<\/p>\n<p>Beneficio adicional: Si vienes del lado norte, disfruta el impresionante panorama del Lago Michigan.<\/p>\n<p>Llega al vecindario temprano para degustar una cena antes de asistir al teatro en <a href=\"http:\/\/promontorychicago.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">The Promontory<\/a>, un animado restaurante, bar y sede de conciertos. Ubicado alrededor de una chimenea con ladrillos, el restaurante ofrece gastronom\u00eda de alto nivel a precios asequibles, desde tartines de tocino y ostiones a la parrilla, hasta pollo de granja con \u00f1oquis parisinos y zanahorias asadas.<\/p>\n<h2>Lincoln Park: dramaturgos americanos en la mira<\/h2>\n<figure id=\"attachment_14219\" aria-describedby=\"caption-attachment-14219\" style=\"width: 1920px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14219\" src=\"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/1_Chicago_theatres-SteppenwolfTheatre.jpg\" alt=\"Steppenwolf\" width=\"1920\" height=\"960\"><figcaption id=\"caption-attachment-14219\" class=\"wp-caption-text\">Steppenwolf ofrece un programa variado. (Foto: Ten Photos)<\/figcaption><\/figure>\n<p>Al igual que Court Theatre, <a href=\"https:\/\/www.steppenwolf.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Steppenwolf Theatre<\/a> comparte el \u00e1rea con una universidad, en este caso la Universidad de DePaul, que ha inspirado a la compa\u00f1\u00eda a ofrecer una programaci\u00f3n variada que atrae a p\u00fablicos de todas las generaciones.<\/p>\n<p>Fundado en 1974 por los actores Gary Sinise, Terry Kinney y Jeff Perry, Steppenwolf presenta en \u2033LookOut Series\u2033 trabajos de todos los g\u00e9neros, adem\u00e1s de sus temporadas regulares de siete obras y representaciones para adultos j\u00f3venes.<\/p>\n<p>Imita a la gente de la localidad y reserva una mesa para antes o despu\u00e9s del espect\u00e1culo en <a href=\"http:\/\/www.bokachicago.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Boka<\/a>, un favorito de la zona que no se queda atr\u00e1s en galardones, incluidas seis Estrellas Michelin consecutivas.<\/p>\n<p>Hazle un homenaje a los \u00e9xitos continuos del men\u00fa de platillos americanos modernos de temporada del chef Lee Wolen, degustando delicias como r\u00f3balo asado con aceitunas negras y ajo verde y betabel (remolacha) asado al carb\u00f3n con semillas de calabaza y regaliz. Y no olvides el postre al final; el sabor de la reposter\u00eda de Meg Galus es tan divertido como su apariencia.<\/p>\n<div class=\"moments-data\" data-city-code=\"Chicago\" data-query=\"\"><\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con m\u00e1s de 40 sedes, producciones aclamadas a nivel nacional y una Semana del Teatro, Chicago, Illinois se erige como uno de los escenarios art\u00edsticos m\u00e1s din\u00e1micos de Estados Unidos.&hellip;<\/p>\n","protected":false},"author":170,"featured_media":14221,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5080,819],"tags":[5050,4006],"class_list":["post-14220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chicago","category-cultura-estilo","tag-chicago","tag-teatro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.5 (Yoast SEO v24.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad<\/title>\n<meta name=\"description\" content=\"An\u00edmate a visitar los cl\u00e1sicos y aclamados barrios art\u00edsticos y teatreros de Chicago. Aqu\u00ed tienes una gu\u00eda, desc\u00fabrelos y disfr\u00fatalos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad\" \/>\n<meta property=\"og:description\" content=\"Con m\u00e1s de 40 sedes, producciones aclamadas a nivel nacional y una Semana del Teatro, Chicago, Illinois se erige como uno de los escenarios art\u00edsticos m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/\" \/>\n<meta property=\"og:site_name\" content=\"Marriott Bonvoy Traveler en Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MarriottBonvoyLatAm\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-27T03:47:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre-1024x512.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicole Schnitzler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mbonvoytraveler\" \/>\n<meta name=\"twitter:site\" content=\"@mbonvoytraveler\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole Schnitzler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/\"},\"author\":{\"name\":\"Nicole Schnitzler\",\"@id\":\"https:\/\/traveler.marriott.com\/es\/#\/schema\/person\/c0054322934f4c201379d640edc14bdd\"},\"headline\":\"Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad\",\"datePublished\":\"2018-10-27T03:47:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/\"},\"wordCount\":774,\"publisher\":{\"@id\":\"https:\/\/traveler.marriott.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre.jpg\",\"keywords\":[\"Chicago\",\"Teatro\"],\"articleSection\":[\"Chicago\",\"Cultura + Estilo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/\",\"url\":\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/\",\"name\":\"Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad\",\"isPartOf\":{\"@id\":\"https:\/\/traveler.marriott.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre.jpg\",\"datePublished\":\"2018-10-27T03:47:46+00:00\",\"description\":\"An\u00edmate a visitar los cl\u00e1sicos y aclamados barrios art\u00edsticos y teatreros de Chicago. Aqu\u00ed tienes una gu\u00eda, desc\u00fabrelos y disfr\u00fatalos.\",\"breadcrumb\":{\"@id\":\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#primaryimage\",\"url\":\"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre.jpg\",\"contentUrl\":\"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre.jpg\",\"width\":1920,\"height\":960,\"caption\":\"Los vecindarios de Chicago est\u00e1n llenos de hallazgos culturales, solo necesitas saber d\u00f3nde buscar. (Foto: Diez Fotos)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/traveler.marriott.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/traveler.marriott.com\/es\/#website\",\"url\":\"https:\/\/traveler.marriott.com\/es\/\",\"name\":\"Marriott Bonvoy Traveler en Espa\u00f1ol\",\"description\":\"Planifica tus viajes con consejos e inspiraci\u00f3n de Marriott Bonvoy Traveler. Perm\u00edtenos ser tu gu\u00eda de viaje para que experimentes ciudades como un lugare\u00f1o.\",\"publisher\":{\"@id\":\"https:\/\/traveler.marriott.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/traveler.marriott.com\/search\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/traveler.marriott.com\/es\/#organization\",\"name\":\"Marriott Bonvoy Traveler en Espa\u00f1ol\",\"url\":\"https:\/\/traveler.marriott.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/traveler.marriott.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2019\/02\/logo-es.png\",\"contentUrl\":\"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2019\/02\/logo-es.png\",\"width\":416,\"height\":172,\"caption\":\"Marriott Bonvoy Traveler en Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\/\/traveler.marriott.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MarriottBonvoyLatAm\",\"https:\/\/x.com\/mbonvoytraveler\",\"https:\/\/www.instagram.com\/marriottbonvoy\/\",\"https:\/\/www.pinterest.com\/marriottbonvoytraveler\/\",\"https:\/\/www.youtube.com\/channel\/UCpDtA9d5Z8SsNEnsVgwq9LA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/traveler.marriott.com\/es\/#\/schema\/person\/c0054322934f4c201379d640edc14bdd\",\"name\":\"Nicole Schnitzler\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad","description":"An\u00edmate a visitar los cl\u00e1sicos y aclamados barrios art\u00edsticos y teatreros de Chicago. Aqu\u00ed tienes una gu\u00eda, desc\u00fabrelos y disfr\u00fatalos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/","og_locale":"es_ES","og_type":"article","og_title":"Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad","og_description":"Con m\u00e1s de 40 sedes, producciones aclamadas a nivel nacional y una Semana del Teatro, Chicago, Illinois se erige como uno de los escenarios art\u00edsticos m\u00e1s","og_url":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/","og_site_name":"Marriott Bonvoy Traveler en Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/MarriottBonvoyLatAm","article_published_time":"2018-10-27T03:47:46+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre-1024x512.jpg","type":"image\/jpeg"}],"author":"Nicole Schnitzler","twitter_card":"summary_large_image","twitter_creator":"@mbonvoytraveler","twitter_site":"@mbonvoytraveler","twitter_misc":{"Escrito por":"Nicole Schnitzler","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#article","isPartOf":{"@id":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/"},"author":{"name":"Nicole Schnitzler","@id":"https:\/\/traveler.marriott.com\/es\/#\/schema\/person\/c0054322934f4c201379d640edc14bdd"},"headline":"Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad","datePublished":"2018-10-27T03:47:46+00:00","mainEntityOfPage":{"@id":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/"},"wordCount":774,"publisher":{"@id":"https:\/\/traveler.marriott.com\/es\/#organization"},"image":{"@id":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#primaryimage"},"thumbnailUrl":"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre.jpg","keywords":["Chicago","Teatro"],"articleSection":["Chicago","Cultura + Estilo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/","url":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/","name":"Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad","isPartOf":{"@id":"https:\/\/traveler.marriott.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#primaryimage"},"image":{"@id":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#primaryimage"},"thumbnailUrl":"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre.jpg","datePublished":"2018-10-27T03:47:46+00:00","description":"An\u00edmate a visitar los cl\u00e1sicos y aclamados barrios art\u00edsticos y teatreros de Chicago. Aqu\u00ed tienes una gu\u00eda, desc\u00fabrelos y disfr\u00fatalos.","breadcrumb":{"@id":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#primaryimage","url":"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre.jpg","contentUrl":"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre.jpg","width":1920,"height":960,"caption":"Los vecindarios de Chicago est\u00e1n llenos de hallazgos culturales, solo necesitas saber d\u00f3nde buscar. (Foto: Diez Fotos)"},{"@type":"BreadcrumbList","@id":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/traveler.marriott.com\/es\/"},{"@type":"ListItem","position":2,"name":"Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad"}]},{"@type":"WebSite","@id":"https:\/\/traveler.marriott.com\/es\/#website","url":"https:\/\/traveler.marriott.com\/es\/","name":"Marriott Bonvoy Traveler en Espa\u00f1ol","description":"Planifica tus viajes con consejos e inspiraci\u00f3n de Marriott Bonvoy Traveler. Perm\u00edtenos ser tu gu\u00eda de viaje para que experimentes ciudades como un lugare\u00f1o.","publisher":{"@id":"https:\/\/traveler.marriott.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/traveler.marriott.com\/search\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/traveler.marriott.com\/es\/#organization","name":"Marriott Bonvoy Traveler en Espa\u00f1ol","url":"https:\/\/traveler.marriott.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/traveler.marriott.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2019\/02\/logo-es.png","contentUrl":"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2019\/02\/logo-es.png","width":416,"height":172,"caption":"Marriott Bonvoy Traveler en Espa\u00f1ol"},"image":{"@id":"https:\/\/traveler.marriott.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MarriottBonvoyLatAm","https:\/\/x.com\/mbonvoytraveler","https:\/\/www.instagram.com\/marriottbonvoy\/","https:\/\/www.pinterest.com\/marriottbonvoytraveler\/","https:\/\/www.youtube.com\/channel\/UCpDtA9d5Z8SsNEnsVgwq9LA"]},{"@type":"Person","@id":"https:\/\/traveler.marriott.com\/es\/#\/schema\/person\/c0054322934f4c201379d640edc14bdd","name":"Nicole Schnitzler"}]}},"acf":{"primary_category":{"term_id":819,"name":"Cultura + Estilo","slug":"cultura-estilo","term_group":0,"term_taxonomy_id":822,"taxonomy":"category","description":"","parent":0,"count":202,"filter":"raw"},"sponsored_article":"no","show_on_homepage":"yes","custom_category_label":"","where_to_stay_links":"<ul>\n<li><a href=\"https:\/\/www.espanol.marriott.com\/hotels\/travel\/chijw-jw-marriott-chicago\" target=\"_blank\" rel=\"noopener\">JW Marriott Chicago<\/a><\/li>\n<li><a href=\"https:\/\/www.espanol.marriott.com\/hotels\/travel\/chidt-chicago-marriott-downtown-magnificent-mile\" target=\"_blank\" rel=\"noopener\">Chicago Marriott Downtown Magnificent Mile<\/a><\/li>\n<li><a href=\"https:\/\/www.espanol.marriott.com\/hotels\/travel\/chimm-courtyard-chicago-downtown-magnificent-mile\" target=\"_blank\" rel=\"noopener\">Courtyard Chicago Downtown\/Magnificent Mile<\/a><\/li>\n<li><a href=\"https:\/\/www.espanol.marriott.com\/hotels\/travel\/chiax-hotel-chicago-downtown-autograph-collection\" target=\"_blank\" rel=\"noopener\">Hotel Chicago Downtown, Autograph Collection<\/a><\/li>\n<\/ul>\n","moments":"","translated_post":{"selected_posts":[14880],"site_id":1},"top_ad_unit":""},"image":{"url":"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre.jpg","width":1920,"height":960,"alt":"","title":"Chicago_theatres-LookingglassTheatre","caption":"Los vecindarios de Chicago est\u00e1n llenos de hallazgos culturales, solo necesitas saber d\u00f3nde buscar. (Foto: Diez Fotos)","sizes":{"thumbnail":{"url":"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre-130x74.jpg","width":130,"height":74},"medium":{"url":"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre-420x210.jpg","width":420,"height":210},"medium_large":{"url":"https:\/\/traveler.marriott.com\/es\/wp-content\/uploads\/sites\/2\/2018\/10\/Chicago_theatres-LookingglassTheatre-768x384.jpg","width":768,"height":384}}},"class":"image-preview-effect top-article post-14220","categories_names":["Chicago","Cultura + Estilo"],"category_label":"Cultura + Estilo","category":"<a href=\"https:\/\/traveler.marriott.com\/es\/cultura-estilo\/\" title=\"Cultura + Estilo\">Cultura + Estilo<\/a>","author_data":"<a href=\"https:\/\/traveler.marriott.com\/es\/autor\/nicole-schnitzler\/\" title=\"Entradas de Nicole Schnitzler\" rel=\"author\">Nicole Schnitzler<\/a>","tags_data":"<a href=\"https:\/\/traveler.marriott.com\/es\/tag\/chicago\/\" rel=\"tag\">Chicago<\/a>, <a href=\"https:\/\/traveler.marriott.com\/es\/tag\/teatro\/\" rel=\"tag\">Teatro<\/a>","sponsored":false,"yoast_meta":{"title":"Teatro en Chicago: encuentra los barrios m\u00e1s art\u00edsticos de la ciudad","metadesc":"An\u00edmate a visitar los cl\u00e1sicos y aclamados barrios art\u00edsticos y teatreros de Chicago. Aqu\u00ed tienes una gu\u00eda, desc\u00fabrelos y disfr\u00fatalos.","canonical":"https:\/\/traveler.marriott.com\/es\/chicago\/teatro-en-chicago\/","locale":"es_ES"},"next":{"name":"barrios-historicos-y-modernos-de-chicago","title":"Tres modernos e hist\u00f3ricos barrios de Chicago que debes visitar"},"previous":{"name":"actividades-y-atracciones-en-houston","title":"Las actividades y atracciones que no te puedes perder en Houston"},"_links":{"self":[{"href":"https:\/\/traveler.marriott.com\/es\/wp-json\/wp\/v2\/posts\/14220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/traveler.marriott.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/traveler.marriott.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/traveler.marriott.com\/es\/wp-json\/wp\/v2\/users\/170"}],"replies":[{"embeddable":true,"href":"https:\/\/traveler.marriott.com\/es\/wp-json\/wp\/v2\/comments?post=14220"}],"version-history":[{"count":0,"href":"https:\/\/traveler.marriott.com\/es\/wp-json\/wp\/v2\/posts\/14220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/traveler.marriott.com\/es\/wp-json\/wp\/v2\/media\/14221"}],"wp:attachment":[{"href":"https:\/\/traveler.marriott.com\/es\/wp-json\/wp\/v2\/media?parent=14220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/traveler.marriott.com\/es\/wp-json\/wp\/v2\/categories?post=14220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/traveler.marriott.com\/es\/wp-json\/wp\/v2\/tags?post=14220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}